{"id":1559,"date":"2023-06-08T09:35:53","date_gmt":"2023-06-08T08:35:53","guid":{"rendered":"https:\/\/mvision.store\/?post_type=product&#038;p=1559"},"modified":"2026-01-16T10:05:34","modified_gmt":"2026-01-16T10:05:34","slug":"hp-pavilion-aero-amd-ryzen-5-7535u-13-3-inch33-8cm-wuxga-ips-micro-edge-laptop16gb-ram-512gb-ssd-amd-radeon-graphics-win-11-mso-backlit-keyboard-bo-fpr-alexa-rose-gold-970-grams-13-be2056au","status":"publish","type":"product","link":"https:\/\/mvision.store\/index.php\/product\/hp-pavilion-aero-amd-ryzen-5-7535u-13-3-inch33-8cm-wuxga-ips-micro-edge-laptop16gb-ram-512gb-ssd-amd-radeon-graphics-win-11-mso-backlit-keyboard-bo-fpr-alexa-rose-gold-970-grams-13-be2056au\/","title":{"rendered":"HP Pavilion Aero AMD Ryzen 5 7535U 13.3 inch(33.8cm) WUXGA IPS Micro-Edge Laptop(16GB RAM\/512GB SSD\/AMD Radeon Graphics\/Win 11\/MSO\/Backlit Keyboard\/B&#038;O\/FPR\/Alexa\/Rose Gold\/970 Grams) 13-be2056AU"},"content":{"rendered":"<p>&nbsp;<\/p>\n<table class=\"a-normal a-spacing-micro\">\n<tbody>\n<tr class=\"a-spacing-small po-brand\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Brand<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">HP<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-model_name\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Model Name<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">13-be2056AU<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-display.size\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Screen Size<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">33.8 Centimetres<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-color\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Colour<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Pale Rose Gold<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-hard_disk.size\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Hard Disk Size<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">512 GB<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-cpu_model.family\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">CPU Model<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Ryzen 5<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-ram_memory.installed_size\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">RAM Memory Installed Size<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">16 GB<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-operating_system\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Operating System<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Windows 11 Home<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-special_feature\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Special Feature<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Fingerprint Reader, Temporal noise reduction, Backlit Keyboard, Micro-Edge Display, Anti-Glare<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-graphics_description\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Graphics Card Description<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Integrated<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<h1 class=\"a-size-base-plus a-text-bold\">About this item<\/h1>\n<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Processor: AMD Ryzen 5 7535U (up to 4.55 GHz max boost clock(2i), 16 MB L3 cache, 6 cores, 12 threads)|Memory: 16 GB LPDDR5-6400 MHz RAM (onboard)|Storage: 512 GB PCIe NVMe M.2 SSD<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Display &amp; Graphics: 33.8 cm (13.3&#8243;) diagonal, WUXGA, IPS, micro-edge, anti-glare,Brightness: 400 nits, 170 ppi,Color Gamut: 100% sRGB,Screen Resolution: 1920 x 1200 |Graphics: AMD Radeon Graphics<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Operating System &amp; Preinstalled Software: Windows 11 Home 64 Plus Single Language|Microsoft Office Home &amp; Student 2021<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Ports:1 USB Type-C 10Gbps signaling rate (USB Power Delivery, DisplayPort 1.4, HP Sleep and Charge); 2 USB Type-A 5Gbps signaling rate; 1 HDMI 2.1; 1 AC smart pin; 1 headphone\/microphone combo<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Other Features: HP Wide Vision 720p HD camera with temporal noise reduction and integrated dual array digital microphones|Networking: Realtek Wi-Fi 6 (2&#215;2) and Bluetooth 5.3 wireless card(Supporting Gigabit data rate)|Keyboard &amp; Pointing Device: Full-size, backlit, Pale Rose Gold keyboard, HP Imagepad with multi-touch gesture support|Battery: 3-cell, 41 Wh Li-ion,Support battery fast charge<\/span><\/li>\n<\/ul>\n","protected":false},"featured_media":1565,"template":"","meta":[],"product_cat":[27],"product_tag":[129],"_links":{"self":[{"href":"https:\/\/mvision.store\/index.php\/wp-json\/wp\/v2\/product\/1559"}],"collection":[{"href":"https:\/\/mvision.store\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mvision.store\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mvision.store\/index.php\/wp-json\/wp\/v2\/media\/1565"}],"wp:attachment":[{"href":"https:\/\/mvision.store\/index.php\/wp-json\/wp\/v2\/media?parent=1559"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mvision.store\/index.php\/wp-json\/wp\/v2\/product_cat?post=1559"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mvision.store\/index.php\/wp-json\/wp\/v2\/product_tag?post=1559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}